{"id":53,"count":1,"description":"","link":"https:\/\/www.lighterlighter.com\/blog\/category\/hp\/","name":"HP","slug":"hp","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.lighterlighter.com\/blog\/wp-json\/wp\/v2\/categories\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lighterlighter.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.lighterlighter.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.lighterlighter.com\/blog\/wp-json\/wp\/v2\/posts?categories=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}